{"id":222,"count":6,"description":"","link":"https:\/\/dankrell.com\/blog\/category\/mortgage-modification\/","name":"mortgage modification","slug":"mortgage-modification","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/dankrell.com\/blog\/wp-json\/wp\/v2\/categories\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dankrell.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dankrell.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dankrell.com\/blog\/wp-json\/wp\/v2\/posts?categories=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}